{"id":5758,"date":"2023-09-26T17:08:37","date_gmt":"2023-09-26T15:08:37","guid":{"rendered":"https:\/\/www.campingduvieuxmoulin.fr\/nachricht\/fort-medoc\/"},"modified":"2024-06-12T13:41:33","modified_gmt":"2024-06-12T11:41:33","slug":"fort-medoc","status":"publish","type":"post","link":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/","title":{"rendered":"Fort M\u00e9doc, ein Kulturerbe, das Sie w\u00e4hrend eines Aufenthalts in der Gironde besuchen sollten"},"content":{"rendered":"<p>Im Herzen des M\u00e9doc, auf halbem Weg zwischen B\u00e9gadan und Bordeaux, liegt Fort M\u00e9doc in Cussac-Fort-M\u00e9doc, am Rande der Gironde-M\u00fcndung. Dieser etwa f\u00fcnfzig Autominuten von Vensac entfernte Ort ist einer der unverzichtbaren Orte, die Sie w\u00e4hrend Ihres Aufenthalts auf unserem Campingplatz im M\u00e9doc besuchen sollten.<\/p>\n<h2>Fort M\u00e9doc, ein Denkmal von gr\u00f6\u00dfter Bedeutung<\/h2>\n<p>Die Gironde-M\u00fcndung war schon immer ein strategischer Standort f\u00fcr die Eroberung der Region. Diese Wasserstra\u00dfe wurde bereits w\u00e4hrend des Wikingereinfalls und w\u00e4hrend der Schlachten im Hundertj\u00e4hrigen Krieg von Feinden genutzt. Aus diesem Grund bat K\u00f6nig Ludwig XIV. seinen Milit\u00e4rarchitekten Vauban um einen Plan zur Verst\u00e4rkung der Verteidigung des Ortes.<\/p>\n<p>Vauban lie\u00df dann die M\u00fcndungsschleuse errichten, ein Verteidigungstriptychon, zu dem das Fort M\u00e9doc geh\u00f6rt. Die anderen beiden sind die Zitadelle von Blaye (Gemeinde Blaye) und Fort P\u00e2t\u00e9 (errichtet auf der Insel P\u00e2t\u00e9 in der Mitte der Flussm\u00fcndung).<\/p>\n<p>Die Aufgabe von Fort M\u00e9doc, der Zitadelle von Blaye und Fort P\u00e2t\u00e9 bestand daher darin, Bordeaux und seinen Hafen zu sch\u00fctzen.<\/p>\n<p>Der Bau der Festung begann im Jahr 1689 und wurde 1694 abgeschlossen. Diese milit\u00e4rische Festung ist seit 1916 entwaffnet. Im Jahr 2008 wurde sie als historisches Denkmal Frankreichs eingestuft und zum UNESCO-Weltkulturerbe erkl\u00e4rt.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/h0Gr0IGjT84?si=fwtxJ8vx8KXi2jDI\" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Besuchen Sie Fort M\u00e9doc, ein Natur- und Kulturausflug f\u00fcr die Familie<\/h2>\n<p>Es gibt zwei M\u00f6glichkeiten, Fort M\u00e9doc zu besuchen: eine selbstgef\u00fchrte Tour mit Hilfe eines Tourenplans und eine Tour mit einem F\u00fchrer (Reservierung erforderlich).<\/p>\n<p>Seit 2020 k\u00f6nnen Besucher \u00fcber eine Augmented-Reality-Anwendung das Fort M\u00e9doc so visualisieren, wie es zu Beginn des 18. Jahrhunderts aussah, und so ein umfassendes Erlebnis im Herzen dieses bedeutenden Erbes der Gironde bieten.<\/p>\n<p>Fort M\u00e9doc ist ein bemerkenswertes Beispiel f\u00fcr die Genialit\u00e4t der milit\u00e4rischen Befestigungen von Vauban. W\u00e4hrend des Besuchs im Fort M\u00e9doc k\u00f6nnen Sie die strategischen und technischen Aspekte der Verteidigung der Gironde-M\u00fcndung entdecken. Sie werden die Bastionen, die Kasematten, die Pulvermagazine erkunden &#8230;<\/p>\n<p>Am Ende Ihres Besuchs sollten Sie nicht abreisen, ohne die Aussicht rund um Fort M\u00e9doc genossen zu haben. Das Fort M\u00e9doc liegt am linken Ufer der Gironde-M\u00fcndung und bietet einen herrlichen Blick auf die M\u00fcndung.<\/p>\n<p>Der Besuch des Fort M\u00e9doc kann mit Besuchen der St\u00e4tten der Zitadelle von Blaye oder des Fort Pat\u00e9 kombiniert werden, sodass ein ganzer Tag der \u201eSchleuse der Flussm\u00fcndung\u201c gewidmet ist.<\/p>\n<h2>Tour zum Kulturerbe der Gironde<\/h2>\n<p>Um die Region Gironde und ihr Erbe (Fort M\u00e9doc, Zitadelle von Blaye, Fort Pat\u00e9) zu besichtigen, \u00fcbernachten Sie auf unserem Campingplatz Le Vieux Moulin, einem charmanten Open-Air-Hotel in der Stadt Vensac im M\u00e9doc.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m28!1m12!1m3!1d179768.1688388182!2d-1.057568678373981!3d45.25026706160755!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m13!3e0!4m5!1s0x480191b7122e6d5d%3A0x4344b1725ae858ee!2sCamping%20*2A*2A%20du%20vieux%20moulin%2C%20Rue%20du%20Moulin%2C%20Vensac!3m2!1d45.398813999999994!2d-1.048179!4m5!1s0x4801d106d6fb39fb%3A0x73bea563e98313a0!2sFort%20M%C3%A9doc%2C%20Av.%20du%20Fort%20M%C3%A9doc%2C%2033460%20Cussac-Fort-M%C3%A9doc!3m2!1d45.109601999999995!2d-0.7055583999999999!5e0!3m2!1sfr!2sfr!4v1695740893855!5m2!1sfr!2sfr\" width=\"100%\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Sie k\u00f6nnen auch die reiche Landschaft der Gironde-M\u00fcndung bewundern. Nehmen Sie dazu einen Teil der Weinstra\u00dfe des M\u00e9doc, die von Vensac \u00fcber Saint-Germain-d\u2019Esteuil nach Cussac-Fort-M\u00e9doc f\u00fchrt.<\/p>\n<p>Planen Sie au\u00dferdem einen Besuch in einigen der sch\u00f6nsten D\u00f6rfer an den Ufern der Gironde-M\u00fcndung ein: Blaye, Margaux, Saint-Est\u00e8phe&#8230; Unterwegs entdecken Sie das Schloss Tour de By, das Schloss von Agassac, das Schloss von Arsac oder das orientalisch inspirierte Schloss Cos d&#8217;Estournel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Herzen des M\u00e9doc, auf halbem Weg zwischen B\u00e9gadan und Bordeaux, liegt Fort M\u00e9doc in Cussac-Fort-M\u00e9doc, am Rande der Gironde-M\u00fcndung. Dieser etwa f\u00fcnfzig Autominuten von Vensac entfernte Ort ist einer der unverzichtbaren Orte, die Sie w\u00e4hrend Ihres Aufenthalts auf unserem Campingplatz im M\u00e9doc besuchen sollten. Fort M\u00e9doc, ein Denkmal von gr\u00f6\u00dfter Bedeutung Die Gironde-M\u00fcndung war [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-5758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fort M\u00e9doc: Besuch dieses Erbes der Gironde im M\u00e9doc<\/title>\n<meta name=\"description\" content=\"Besuchen Sie w\u00e4hrend Ihres Aufenthalts auf unserem Campingplatz in der Gironde das Fort M\u00e9doc de Vauban, ein bedeutendes historisches Denkmal im M\u00e9doc\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fort M\u00e9doc: Besuch dieses Erbes der Gironde im M\u00e9doc\" \/>\n<meta property=\"og:description\" content=\"Besuchen Sie w\u00e4hrend Ihres Aufenthalts auf unserem Campingplatz in der Gironde das Fort M\u00e9doc de Vauban, ein bedeutendes historisches Denkmal im M\u00e9doc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping du Vieux Moulin\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-26T15:08:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T11:41:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campingduvieuxmoulin.fr\/wp-content\/uploads\/2023\/09\/fort-medoc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sophie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sophie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/\"},\"author\":{\"name\":\"Sophie\",\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/es\\\/#\\\/schema\\\/person\\\/5677ba601628886ef9b02a5c26cf08e2\"},\"headline\":\"Fort M\u00e9doc, ein Kulturerbe, das Sie w\u00e4hrend eines Aufenthalts in der Gironde besuchen sollten\",\"datePublished\":\"2023-09-26T15:08:37+00:00\",\"dateModified\":\"2024-06-12T11:41:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/\"},\"wordCount\":549,\"image\":{\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/fort-medoc.jpg\",\"articleSection\":[\"Nachricht\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/\",\"url\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/\",\"name\":\"Fort M\u00e9doc: Besuch dieses Erbes der Gironde im M\u00e9doc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/fort-medoc.jpg\",\"datePublished\":\"2023-09-26T15:08:37+00:00\",\"dateModified\":\"2024-06-12T11:41:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/es\\\/#\\\/schema\\\/person\\\/5677ba601628886ef9b02a5c26cf08e2\"},\"description\":\"Besuchen Sie w\u00e4hrend Ihres Aufenthalts auf unserem Campingplatz in der Gironde das Fort M\u00e9doc de Vauban, ein bedeutendes historisches Denkmal im M\u00e9doc\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/fort-medoc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/fort-medoc.jpg\",\"width\":1500,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/fort-medoc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Camping Gironde\",\"item\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachricht\",\"item\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/nachricht\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fort M\u00e9doc, ein Kulturerbe, das Sie w\u00e4hrend eines Aufenthalts in der Gironde besuchen sollten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/es\\\/\",\"name\":\"Camping du Vieux Moulin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campingduvieuxmoulin.fr\\\/de\\\/es\\\/#\\\/schema\\\/person\\\/5677ba601628886ef9b02a5c26cf08e2\",\"name\":\"Sophie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84bf56dd40cf360402d79e57ea8d28846acf90be29603f907e5e9967dd281011?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84bf56dd40cf360402d79e57ea8d28846acf90be29603f907e5e9967dd281011?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84bf56dd40cf360402d79e57ea8d28846acf90be29603f907e5e9967dd281011?s=96&d=mm&r=g\",\"caption\":\"Sophie\"},\"sameAs\":[\"http:\\\/\\\/www.campingduvieuxmoulin.fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fort M\u00e9doc: Besuch dieses Erbes der Gironde im M\u00e9doc","description":"Besuchen Sie w\u00e4hrend Ihres Aufenthalts auf unserem Campingplatz in der Gironde das Fort M\u00e9doc de Vauban, ein bedeutendes historisches Denkmal im M\u00e9doc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/","og_locale":"de_DE","og_type":"article","og_title":"Fort M\u00e9doc: Besuch dieses Erbes der Gironde im M\u00e9doc","og_description":"Besuchen Sie w\u00e4hrend Ihres Aufenthalts auf unserem Campingplatz in der Gironde das Fort M\u00e9doc de Vauban, ein bedeutendes historisches Denkmal im M\u00e9doc","og_url":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/","og_site_name":"Camping du Vieux Moulin","article_published_time":"2023-09-26T15:08:37+00:00","article_modified_time":"2024-06-12T11:41:33+00:00","og_image":[{"width":1500,"height":680,"url":"https:\/\/www.campingduvieuxmoulin.fr\/wp-content\/uploads\/2023\/09\/fort-medoc.jpg","type":"image\/jpeg"}],"author":"Sophie","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sophie","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/#article","isPartOf":{"@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/"},"author":{"name":"Sophie","@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/es\/#\/schema\/person\/5677ba601628886ef9b02a5c26cf08e2"},"headline":"Fort M\u00e9doc, ein Kulturerbe, das Sie w\u00e4hrend eines Aufenthalts in der Gironde besuchen sollten","datePublished":"2023-09-26T15:08:37+00:00","dateModified":"2024-06-12T11:41:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/"},"wordCount":549,"image":{"@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campingduvieuxmoulin.fr\/wp-content\/uploads\/2023\/09\/fort-medoc.jpg","articleSection":["Nachricht"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/","url":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/","name":"Fort M\u00e9doc: Besuch dieses Erbes der Gironde im M\u00e9doc","isPartOf":{"@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/#primaryimage"},"image":{"@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campingduvieuxmoulin.fr\/wp-content\/uploads\/2023\/09\/fort-medoc.jpg","datePublished":"2023-09-26T15:08:37+00:00","dateModified":"2024-06-12T11:41:33+00:00","author":{"@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/es\/#\/schema\/person\/5677ba601628886ef9b02a5c26cf08e2"},"description":"Besuchen Sie w\u00e4hrend Ihres Aufenthalts auf unserem Campingplatz in der Gironde das Fort M\u00e9doc de Vauban, ein bedeutendes historisches Denkmal im M\u00e9doc","breadcrumb":{"@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/#primaryimage","url":"https:\/\/www.campingduvieuxmoulin.fr\/wp-content\/uploads\/2023\/09\/fort-medoc.jpg","contentUrl":"https:\/\/www.campingduvieuxmoulin.fr\/wp-content\/uploads\/2023\/09\/fort-medoc.jpg","width":1500,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/fort-medoc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Camping Gironde","item":"https:\/\/www.campingduvieuxmoulin.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Nachricht","item":"https:\/\/www.campingduvieuxmoulin.fr\/de\/nachricht\/"},{"@type":"ListItem","position":3,"name":"Fort M\u00e9doc, ein Kulturerbe, das Sie w\u00e4hrend eines Aufenthalts in der Gironde besuchen sollten"}]},{"@type":"WebSite","@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/es\/#website","url":"https:\/\/www.campingduvieuxmoulin.fr\/de\/es\/","name":"Camping du Vieux Moulin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campingduvieuxmoulin.fr\/de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.campingduvieuxmoulin.fr\/de\/es\/#\/schema\/person\/5677ba601628886ef9b02a5c26cf08e2","name":"Sophie","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/84bf56dd40cf360402d79e57ea8d28846acf90be29603f907e5e9967dd281011?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84bf56dd40cf360402d79e57ea8d28846acf90be29603f907e5e9967dd281011?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84bf56dd40cf360402d79e57ea8d28846acf90be29603f907e5e9967dd281011?s=96&d=mm&r=g","caption":"Sophie"},"sameAs":["http:\/\/www.campingduvieuxmoulin.fr"]}]}},"_links":{"self":[{"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/posts\/5758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/comments?post=5758"}],"version-history":[{"count":1,"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/posts\/5758\/revisions"}],"predecessor-version":[{"id":5762,"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/posts\/5758\/revisions\/5762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/media\/5055"}],"wp:attachment":[{"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/media?parent=5758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/categories?post=5758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campingduvieuxmoulin.fr\/de\/wp-json\/wp\/v2\/tags?post=5758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}